{"id":8926,"date":"2021-09-02T13:21:39","date_gmt":"2021-09-02T11:21:39","guid":{"rendered":"https:\/\/www.pir.sik.si\/2021\/09\/02\/razstava-migracije-v-izlozbenih-oknih-piranske-knjiznice\/"},"modified":"2021-09-07T11:49:13","modified_gmt":"2021-09-07T09:49:13","slug":"la-mostra-migrazione-nella-biblioteca-civica-pirano","status":"publish","type":"post","link":"https:\/\/www.pir.sik.si\/it\/2021\/09\/02\/la-mostra-migrazione-nella-biblioteca-civica-pirano\/","title":{"rendered":"LA MOSTRA \u00bbMIGRAZIONE\u00ab NELLA BIBLIOTECA CIVICA PIRANO"},"content":{"rendered":"<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\">Matja\u017e Borovni\u010dar \u00e8 nato il 22 giugno 1974 a Capodistria. Nel 1999 si laurea in pittura e storia dell&#8217;arte presso l&#8217;Accademia di Belle Arti di Venezia. Dopo l&#8217;Accademia nel 2002 ha completato i suoi studi in restauro di murales e museologia presso l&#8217;Universit\u00e0 internazionale dell&#8217;arte di Venezia. L&#8217;anno successivo ha completato la sua formazione pedagogica e andragogica presso la Facolt\u00e0 di Lettere di Lubiana. Insegna belle arti e conduce laboratori creativi. Ha partecipato a diverse mostre collettive in patria e all&#8217;estero e ha avuto diverse presentazioni personali. Vive e lavora a Pirano.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\">\u00bbBorovni\u010dar offre le conseguenze di un rituale premuroso. La matrice non ha pi\u00f9 importanza. La mutazione diventa originale, UN SUSSURRO DISCRETO ALIMENTA UNA STORIA DI LIBERTA&#8217;. La situazione \u00e8 innescata dall&#8217;istinto e dalla cognizione. Prosegue con l&#8217;attivit\u00e0 artistica: incisione e rilievo su linoleum. L&#8217;autore Matja\u017e Borovni\u010dar presenta un progetto la cui spina dorsale \u00e8 costituita da stampe grafiche di una rara forma lineare di farfalle. In molte opere riconosciamo un repertorio segnico ridotto a forme mutanti. L&#8217;artista non pone limiti alla quantit\u00e0 di componenti della presentazione, ma rispetta le dimensioni dello spazio espositivo. Le farfalle hanno il codice genetico del nomadismo. Siamo consapevoli che la forma offerta non \u00e8 una forma ma un simbolo che ricorda un vuoto personale. L&#8217;autore valica alternativamente i confini della ricerca sulla percezione individuale del problema e la fenomenologia generale della libert\u00e0 di movimento. Qui \u00e8 dove la storia in realt\u00e0 inizia e finisce.\u00ab Eugen Borokovsky<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><a href=\"https:\/\/piran.knjiznice.si\/2021\/09\/20210902_103738-scaled-e1630581633809.jpg\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-8907 size-medium\" src=\"https:\/\/piran.knjiznice.si\/2021\/09\/20210902_103738-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" \/><\/a><a href=\"https:\/\/piran.knjiznice.si\/2021\/09\/20210901_184211-scaled-e1630581686172.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone wp-image-8905 size-medium\" src=\"https:\/\/piran.knjiznice.si\/2021\/09\/20210901_184211-scaled-e1630581686172-283x300.jpg\" alt=\"\" width=\"283\" height=\"300\" srcset=\"https:\/\/piran.knjiznice.si\/2021\/09\/20210901_184211-scaled-e1630581686172-283x300.jpg 283w, https:\/\/piran.knjiznice.si\/2021\/09\/20210901_184211-scaled-e1630581686172.jpg 373w\" sizes=\"(max-width: 283px) 100vw, 283px\" \/><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Matja\u017e Borovni\u010dar \u00e8 nato il 22 giugno 1974 a Capodistria. Nel 1999 si laurea in pittura e storia dell&#8217;arte presso l&#8217;Accademia di Belle Arti di Venezia. Dopo l&#8217;Accademia nel 2002 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8915,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[41],"tags":[],"class_list":["post-8926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esposizioni-mostre"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.pir.sik.si\/it\/wp-json\/wp\/v2\/posts\/8926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pir.sik.si\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pir.sik.si\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pir.sik.si\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pir.sik.si\/it\/wp-json\/wp\/v2\/comments?post=8926"}],"version-history":[{"count":3,"href":"https:\/\/www.pir.sik.si\/it\/wp-json\/wp\/v2\/posts\/8926\/revisions"}],"predecessor-version":[{"id":9025,"href":"https:\/\/www.pir.sik.si\/it\/wp-json\/wp\/v2\/posts\/8926\/revisions\/9025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pir.sik.si\/it\/wp-json\/wp\/v2\/media\/8915"}],"wp:attachment":[{"href":"https:\/\/www.pir.sik.si\/it\/wp-json\/wp\/v2\/media?parent=8926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pir.sik.si\/it\/wp-json\/wp\/v2\/categories?post=8926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pir.sik.si\/it\/wp-json\/wp\/v2\/tags?post=8926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}